{"id":869,"date":"2020-04-28T16:40:32","date_gmt":"2020-04-28T14:40:32","guid":{"rendered":"https:\/\/www.obgc.unibs.it\/osservatorio\/?p=869"},"modified":"2020-04-28T16:40:33","modified_gmt":"2020-04-28T14:40:33","slug":"ordinanza-del-4-ottobre-2018-presidente-dott-raffaele-del-porto-giudice-relatore-dott-davide-scaffidi","status":"publish","type":"post","link":"https:\/\/www.obgc.unibs.it\/osservatorio\/index.php\/2020\/04\/28\/ordinanza-del-4-ottobre-2018-presidente-dott-raffaele-del-porto-giudice-relatore-dott-davide-scaffidi\/","title":{"rendered":"Ordinanza del 4 ottobre 2018 \u2013 Presidente: Dott. Raffaele Del Porto \u2013 Giudice relatore: Dott. Davide Scaffidi"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/www.obgc.unibs.it\/osservatorio\/index.php\/wp-json\/wp\/v2\/posts\/869?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.obgc.unibs.it\/osservatorio\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Visualizza PDF\" \/><\/a><a href=\"https:\/\/www.obgc.unibs.it\/osservatorio\/index.php\/wp-json\/wp\/v2\/posts\/869?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.obgc.unibs.it\/osservatorio\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Stampa contenuto\" \/><\/a><\/div>\n<p>Dal punto di vista metodologico, l\u2019esame comparativo tra segni distintivi asseritamente identici o similari deve essere condotto non gi\u00e0 mediante l\u2019analisi parcellizzata dei singoli elementi di valutazione, ma in via unitaria e sintetica, attraverso un apprezzamento complessivo che tenga conto degli elementi dotati di capacit\u00e0 evocativa.<\/p>\n\n\n\n<p>Ai fini della valutazione della confondibilit\u00e0 fra segni in conflitto il normale grado di percezione delle persone alle quali il prodotto \u00e8 destinato deve essere parametrato allo specifico settore merceologico nel quale le imprese operano, ben potendosi ritenere quale consumatore medio di riferimento un consumatore qualificato, la cui diligenza e avvedutezza siano tali da ritenere che non si presenti in concreto un rischio di confusione o di associazione tra i rispettivi segni.&nbsp;<\/p>\n\n\n\n<p><em>Principi espressi dal Tribunale che, in accoglimento del reclamo, ha revocato l\u2019ordinanza con la quale era stato inibito l\u2019utilizzo di segni per presunta contraffazione di marchi comunitari (oggi marchi dell\u2019Unione europea) registrati.&nbsp;<\/em><\/p>\n\n\n\n<p><em>In particolare \u00e8 stato affermato che, pur potendosi ravvisare somiglianze non marginali tra i rispettivi segni, sia sotto il profilo grafico, che fonetico, simili analogie non investono la portata evocativa complessiva dei rispettivi segni, attenendo esse a profili funzionali ancillari privi di originalit\u00e0 e distintivit\u00e0. Il collegio ha precisato che ad una valutazione globale, ipoteticamente condotta dal consumatore medio sulla scorta della percezione visiva, i grafemi risultavano tra loro eterogenei e a livello semantico i&nbsp;<\/em>claims<em>&nbsp;dei segni veicolavano concetti differenti, in quanto il primo<s>,<\/s>sarebbe stato volto ad esprimere un messaggio di tipo esortativo, tipo slogan, mentre il secondo si sarebbe limitato a richiamare alla mente del pubblico il profilo della provenienza \u201ccreativa\u201d del prodotto.&nbsp;<\/em><\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/www.obgc.unibs.it\/osservatorio\/wp-content\/uploads\/2020\/04\/Ord.-4.10.2018.pdf\">Ord. 4.10.2018<\/a><a href=\"https:\/\/www.obgc.unibs.it\/osservatorio\/wp-content\/uploads\/2020\/04\/Ord.-4.10.2018.pdf\" class=\"wp-block-file__button\" download>Download<\/a><\/div>\n\n\n\n<p>(Massime a cura di Francesco Maria Maffezzoni)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal punto di vista metodologico, l\u2019esame comparativo tra segni distintivi asseritamente identici o similari deve essere condotto non gi\u00e0 mediante l\u2019analisi parcellizzata dei singoli elementi di valutazione, ma in via unitaria e sintetica, attraverso un apprezzamento complessivo che tenga conto degli elementi dotati di capacit\u00e0 evocativa. Ai fini della valutazione della confondibilit\u00e0 fra segni in [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[650],"tags":[145,654,643,652,653,651],"class_list":["post-869","post","type-post","status-publish","format-standard","hentry","category-marchi","tag-art-2598-c-c","tag-art-9-reg-ue-2017-1001","tag-azione-inibitoria","tag-concorrenza-sleale-confusoria","tag-contraffazione","tag-marchio-comunitario-oggi-marchio-dellunione-europea-registrato"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.obgc.unibs.it\/osservatorio\/index.php\/wp-json\/wp\/v2\/posts\/869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.obgc.unibs.it\/osservatorio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.obgc.unibs.it\/osservatorio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.obgc.unibs.it\/osservatorio\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.obgc.unibs.it\/osservatorio\/index.php\/wp-json\/wp\/v2\/comments?post=869"}],"version-history":[{"count":1,"href":"https:\/\/www.obgc.unibs.it\/osservatorio\/index.php\/wp-json\/wp\/v2\/posts\/869\/revisions"}],"predecessor-version":[{"id":871,"href":"https:\/\/www.obgc.unibs.it\/osservatorio\/index.php\/wp-json\/wp\/v2\/posts\/869\/revisions\/871"}],"wp:attachment":[{"href":"https:\/\/www.obgc.unibs.it\/osservatorio\/index.php\/wp-json\/wp\/v2\/media?parent=869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.obgc.unibs.it\/osservatorio\/index.php\/wp-json\/wp\/v2\/categories?post=869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.obgc.unibs.it\/osservatorio\/index.php\/wp-json\/wp\/v2\/tags?post=869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}